{"id":302,"date":"2017-07-02T22:10:22","date_gmt":"2017-07-02T20:10:22","guid":{"rendered":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo.jpg"},"modified":"2017-07-02T22:10:22","modified_gmt":"2017-07-02T20:10:22","slug":"moeck-logo","status":"inherit","type":"attachment","link":"https:\/\/geigenbau-buennagel.com\/de\/partner\/moeck-logo\/","title":{"rendered":"Moeck Logo"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-302","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Moeck Logo - Geigenbau B\u00fcnnagel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moeck Logo - Geigenbau B\u00fcnnagel\" \/>\n<meta property=\"og:site_name\" content=\"Geigenbau B\u00fcnnagel\" \/>\n<meta property=\"og:image\" content=\"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":null,\"url\":null,\"name\":\"Moeck Logo - Geigenbau B\u00fcnnagel\",\"isPartOf\":{\"@id\":\"https:\/\/geigenbau-buennagel.com\/de\/#website\"},\"datePublished\":\"2017-07-02T20:10:22+00:00\",\"breadcrumb\":{\"@id\":\"#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[null]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Partner\",\"item\":\"https:\/\/geigenbau-buennagel.com\/de\/partner\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Moeck Logo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/geigenbau-buennagel.com\/de\/#website\",\"url\":\"https:\/\/geigenbau-buennagel.com\/de\/\",\"name\":\"Geigenbau B\u00fcnnagel\",\"description\":\"Verkauf, Verleih, Reparatur, Restauration hochwertiger Streichinstrumente seit 1929\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/geigenbau-buennagel.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Moeck Logo - Geigenbau B\u00fcnnagel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Moeck Logo - Geigenbau B\u00fcnnagel","og_site_name":"Geigenbau B\u00fcnnagel","og_image":[{"width":768,"height":533,"url":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":null,"url":null,"name":"Moeck Logo - Geigenbau B\u00fcnnagel","isPartOf":{"@id":"https:\/\/geigenbau-buennagel.com\/de\/#website"},"datePublished":"2017-07-02T20:10:22+00:00","breadcrumb":{"@id":"#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":[null]}]},{"@type":"BreadcrumbList","@id":"#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Partner","item":"https:\/\/geigenbau-buennagel.com\/de\/partner\/"},{"@type":"ListItem","position":2,"name":"Moeck Logo"}]},{"@type":"WebSite","@id":"https:\/\/geigenbau-buennagel.com\/de\/#website","url":"https:\/\/geigenbau-buennagel.com\/de\/","name":"Geigenbau B\u00fcnnagel","description":"Verkauf, Verleih, Reparatur, Restauration hochwertiger Streichinstrumente seit 1929","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/geigenbau-buennagel.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"208\" src=\"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo-300x208.jpg\" class=\"attachment-medium size-medium\" alt=\"Moeck Logo\" srcset=\"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo-300x208.jpg 300w, https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo.jpg 768w, https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo-450x312.jpg 450w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Moeck Logo","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":768,"height":533,"file":"2017\/06\/Moeck-Logo.jpg","sizes":{"thumbnail":{"file":"Moeck-Logo-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo-150x150.jpg"},"medium":{"file":"Moeck-Logo-300x208.jpg","width":300,"height":208,"mime_type":"image\/jpeg","source_url":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo-300x208.jpg"},"medium_large":{"file":"Moeck-Logo-768x533.jpg","width":768,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo-768x533.jpg"},"ug_big":{"file":"Moeck-Logo-768x533.jpg","width":768,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo-768x533.jpg"},"post-thumbnail":{"file":"Moeck-Logo-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo-100x100.jpg"},"fullwidth-landscape":{"file":"Moeck-Logo-768x500.jpg","width":768,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo-768x500.jpg"},"sidebar-landscape":{"file":"Moeck-Logo-768x380.jpg","width":768,"height":380,"mime_type":"image\/jpeg","source_url":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo-768x380.jpg"},"portfolio-square":{"file":"Moeck-Logo-450x350.jpg","width":450,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo-450x350.jpg"},"portfolio-auto":{"file":"Moeck-Logo-450x312.jpg","width":450,"height":312,"mime_type":"image\/jpeg","source_url":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo-450x312.jpg"},"square":{"file":"Moeck-Logo-270x270.jpg","width":270,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo-270x270.jpg"},"full":{"file":"Moeck-Logo.jpg","width":768,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":26,"source_url":"https:\/\/geigenbau-buennagel.com\/de\/wp-content\/uploads\/2017\/06\/Moeck-Logo.jpg","_links":{"self":[{"href":"https:\/\/geigenbau-buennagel.com\/de\/wp-json\/wp\/v2\/media\/302"}],"collection":[{"href":"https:\/\/geigenbau-buennagel.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/geigenbau-buennagel.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/geigenbau-buennagel.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/geigenbau-buennagel.com\/de\/wp-json\/wp\/v2\/comments?post=302"}]}}